{"id":497,"date":"2026-06-30T15:43:27","date_gmt":"2026-06-30T13:43:27","guid":{"rendered":"https:\/\/simonemessori.it\/?p=497"},"modified":"2026-07-17T15:45:25","modified_gmt":"2026-07-17T13:45:25","slug":"dazio-forfetario-di-3-euro-sulle-piccole-spedizioni-extra-ue-nuove-regole-dal-1-luglio","status":"publish","type":"post","link":"https:\/\/simonemessori.it\/en\/2026\/06\/30\/dazio-forfetario-di-3-euro-sulle-piccole-spedizioni-extra-ue-nuove-regole-dal-1-luglio\/","title":{"rendered":"Dazio forfetario di 3 euro sulle piccole spedizioni extra UE: nuove regole dal 1\u00b0 luglio"},"content":{"rendered":"<p class=\"wp-block-paragraph\">Da domani entra in vigore il dazio forfetario di 3 euro per articolo sulle spedizioni e-commerce provenienti da Paesi extra UE, introdotto dal Regolamento UE 2026\/382 in via temporanea fino al 1\u00b0 luglio 2028. La novit\u00e0 riguarda le vendite a distanza di beni con valore intrinseco fino a 150 euro, finora esenti da dazio grazie alla clausola &#8220;de minimis&#8221;, e si applica a tutte le operazioni gestite tramite lo schema IOSS o per via postale, indipendentemente dal valore della merce (da 1 a 150 euro).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Il dazio, qualificandosi come diritto doganale, \u00e8 soggetto a IVA (salvo le ipotesi IOSS) e si applica per ogni riga di dichiarazione doganale, a prescindere dal numero di articoli, purch\u00e9 il valore intrinseco complessivo non superi la soglia dei 150 euro. La misura si inserisce in un pi\u00f9 ampio pacchetto di riforme doganali europee che, tra il 2026 e il 2027, introdurr\u00e0 anche i nuovi product identifiers, il concetto di &#8220;deemed importer&#8221; e una handling fee aggiuntiva (quest&#8217;ultima rinviata in Italia), ponendo il commercio elettronico al centro del nuovo sistema di controlli doganali.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a9 2026 Simone Messori \u2013 Dottore Commercialista e Revisore Legale. Tutti i diritti riservati. \u00c8 vietata la riproduzione, anche parziale, senza autorizzazione scritta dell&#8217;autore.<\/p>","protected":false},"excerpt":{"rendered":"<p>Da domani entra in vigore il dazio forfetario di 3 euro per articolo sulle spedizioni e-commerce provenienti da Paesi extra [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[10],"tags":[],"class_list":["post-497","post","type-post","status-publish","format-standard","hentry","category-internazionale"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Simone Messori","author_link":"https:\/\/simonemessori.it\/en\/author\/user23094004474510\/"},"uagb_comment_info":0,"uagb_excerpt":"Da domani entra in vigore il dazio forfetario di 3 euro per articolo sulle spedizioni e-commerce provenienti da Paesi extra [&hellip;]","_links":{"self":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts\/497","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/comments?post=497"}],"version-history":[{"count":4,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts\/497\/revisions"}],"predecessor-version":[{"id":676,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts\/497\/revisions\/676"}],"wp:attachment":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/media?parent=497"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/categories?post=497"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/tags?post=497"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}