{"id":596,"date":"2026-07-10T10:15:40","date_gmt":"2026-07-10T08:15:40","guid":{"rendered":"https:\/\/simonemessori.it\/?p=596"},"modified":"2026-07-17T15:44:36","modified_gmt":"2026-07-17T13:44:36","slug":"conferimenti-a-realizzo-controllato-quando-la-target-e-estera-attenzione-alla-doppia-imposizione","status":"publish","type":"post","link":"https:\/\/simonemessori.it\/en\/2026\/07\/10\/conferimenti-a-realizzo-controllato-quando-la-target-e-estera-attenzione-alla-doppia-imposizione\/","title":{"rendered":"Conferimenti a realizzo controllato: quando la target \u00e8 estera, attenzione alla doppia imposizione"},"content":{"rendered":"<p class=\"wp-block-paragraph\">I conferimenti a realizzo controllato di partecipazioni, disciplinati dai commi 2 e seguenti dell&#8217;art. 177 del TUIR, hanno conosciuto negli ultimi anni una serie di modifiche rilevanti grazie al D.Lgs. 13 dicembre 2024 n. 192, poi accompagnate da interventi interpretativi contenuti nel successivo D.Lgs. 18 dicembre 2025 n. 192 \u2014 e in attesa, sulla base di una bozza di decreto correttivo Omnibus, di ulteriori parziali riscritture.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">L&#8217;apertura alle partecipazioni in societ\u00e0 estere<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Tra le principali novit\u00e0 di riforma vi \u00e8 l&#8217;apertura del legislatore all&#8217;applicazione del regime anche quando le partecipazioni conferite sono detenute in una societ\u00e0 non residente in Italia. L&#8217;art. 177, comma 2, del TUIR \u2014 da cui deriva anche la variante del comma 2-bis \u2014 nella sua formulazione attuale ammette infatti che la conferitaria acquisisca o incrementi la percentuale di controllo (secondo i criteri dell&#8217;art. 2359, comma 1, n. 1, del codice civile) anche rispetto a una societ\u00e0 estera rientrante nell&#8217;art. 73, comma 1, lett. d), del TUIR.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Questa possibilit\u00e0, un tempo esclusa dalla prassi (risoluzione 4 aprile 2017 n. 43), era in realt\u00e0 gi\u00e0 stata ammessa nell&#8217;ambito dei conferimenti di partecipazioni di controllo e collegamento disciplinati dall&#8217;art. 175 del TUIR. La crescente diffusione di conferimenti di azioni o quote da parte di persone fisiche non imprenditori, oggi attratti nell&#8217;orbita dell&#8217;art. 177, rende per\u00f2 queste questioni molto pi\u00f9 concrete che in passato.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Il limite &#8220;gerarchico&#8221; rispetto agli scambi intracomunitari<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Assonime, nella circolare n. 10 del 29 aprile 2025, osserva come l&#8217;art. 177, comma 2, del TUIR incontri un limite &#8220;gerarchico&#8221; nei casi gi\u00e0 regolati specificamente dalla disciplina degli scambi intracomunitari di partecipazioni. Di conseguenza, i regimi di neutralit\u00e0 indotta dovrebbero applicarsi solo quando sul tavolo vi siano azioni o quote di societ\u00e0 extra-UE, oppure quando manchino i requisiti per invocare la neutralit\u00e0 comunitaria assoluta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assonime evidenzia inoltre come la necessit\u00e0 di un&#8217;assemblea ordinaria presso la societ\u00e0 conferita (requisito del comma 2) renda plausibile che quest&#8217;ultima, se estera, debba essere una societ\u00e0 di capitali residente in un Paese collaborativo, in modo da garantire alle autorit\u00e0 italiane ogni possibilit\u00e0 di verifica.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Il vero rischio: la doppia imposizione nello Stato della target<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">Il profilo pi\u00f9 delicato riguarda le conseguenze del conferimento nello Stato di residenza della societ\u00e0 target. \u00c8 probabile che l&#8217;operazione, pur neutrale in Italia, venga considerata realizzativa all&#8217;estero, a valori di mercato. Se non ricorrono esenzioni interne e la Convenzione contro le doppie imposizioni legittima la tassazione in entrambi gli Stati, l&#8217;imposta pagata all&#8217;estero pu\u00f2 risultare, di fatto, un esborso irrecuperabile in Italia.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Un esempio concreto.<\/strong> Si pensi a un socio di controllo di una societ\u00e0 immobiliare statunitense, con una partecipazione avente costo fiscale di 100 e valore normale di 1.000. Se questi conferisse la partecipazione in una societ\u00e0 italiana applicando la neutralit\u00e0 indotta dell&#8217;art. 177, comma 2, azzerando la plusvalenza di 900 ai fini delle imposte italiane, l&#8217;eventuale tassazione americana successiva (in capo alla holding italiana che cedesse la partecipazione realizzando la stessa plusvalenza) non sarebbe detraibile dall&#8217;IRES, perch\u00e9 scontata da un contribuente diverso \u2014 un problema aggravato dalla mancanza di accesso alla participation exemption.<\/p>\n\n\n\n<h5 class=\"wp-block-heading\">Una possibile via d&#8217;uscita<\/h5>\n\n\n\n<p class=\"wp-block-paragraph\">In questi scenari pu\u00f2 risultare preferibile procedere a iscrizioni in capo alla conferitaria coerenti con i valori peritali delle partecipazioni, in modo da generare una plusvalenza tassata da subito in entrambi i Paesi, in capo al medesimo soggetto (il conferente). La strada per il credito d&#8217;imposta non sarebbe agevole, vista l&#8217;applicazione in Italia di un&#8217;imposta sostitutiva, ma \u2014 sulla base del Trattato e della giurisprudenza pi\u00f9 recente \u2014 non risulterebbe preclusa in partenza.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00a9 2026 Simone Messori \u2013 Dottore Commercialista e Revisore Legale. Tutti i diritti riservati. \u00c8 vietata la riproduzione, anche parziale, senza autorizzazione scritta dell&#8217;autore.<\/p>","protected":false},"excerpt":{"rendered":"<p>I conferimenti a realizzo controllato di partecipazioni, disciplinati dai commi 2 e seguenti dell&#8217;art. 177 del TUIR, hanno conosciuto negli [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_uag_custom_page_level_css":"","site-sidebar-layout":"default","site-content-layout":"","ast-site-content-layout":"default","site-content-style":"default","site-sidebar-style":"default","ast-global-header-display":"","ast-banner-title-visibility":"","ast-main-header-display":"","ast-hfb-above-header-display":"","ast-hfb-below-header-display":"","ast-hfb-mobile-header-display":"","site-post-title":"","ast-breadcrumbs-content":"","ast-featured-img":"","footer-sml-layout":"","ast-disable-related-posts":"","theme-transparent-header-meta":"","adv-header-id-meta":"","stick-header-meta":"","header-above-stick-meta":"","header-main-stick-meta":"","header-below-stick-meta":"","astra-migrate-meta-layouts":"default","ast-page-background-enabled":"default","ast-page-background-meta":{"desktop":{"background-color":"var(--ast-global-color-5)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"ast-content-background-meta":{"desktop":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"tablet":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""},"mobile":{"background-color":"var(--ast-global-color-4)","background-image":"","background-repeat":"repeat","background-position":"center center","background-size":"auto","background-attachment":"scroll","background-type":"","background-media":"","overlay-type":"","overlay-color":"","overlay-opacity":"","overlay-gradient":""}},"footnotes":""},"categories":[12,10],"tags":[],"class_list":["post-596","post","type-post","status-publish","format-standard","hentry","category-fiscale","category-internazionale"],"uagb_featured_image_src":{"full":false,"thumbnail":false,"medium":false,"medium_large":false,"large":false,"1536x1536":false,"2048x2048":false,"trp-custom-language-flag":false},"uagb_author_info":{"display_name":"Simone Messori","author_link":"https:\/\/simonemessori.it\/en\/author\/user23094004474510\/"},"uagb_comment_info":0,"uagb_excerpt":"I conferimenti a realizzo controllato di partecipazioni, disciplinati dai commi 2 e seguenti dell&#8217;art. 177 del TUIR, hanno conosciuto negli [&hellip;]","_links":{"self":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts\/596","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/comments?post=596"}],"version-history":[{"count":5,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts\/596\/revisions"}],"predecessor-version":[{"id":670,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/posts\/596\/revisions\/670"}],"wp:attachment":[{"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/media?parent=596"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/categories?post=596"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/simonemessori.it\/en\/wp-json\/wp\/v2\/tags?post=596"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}